{"id":3784,"date":"2026-07-07T19:11:57","date_gmt":"2026-07-07T19:11:57","guid":{"rendered":"https:\/\/mosareldecor.com\/?post_type=product&#038;p=3784"},"modified":"2026-07-08T18:18:50","modified_gmt":"2026-07-08T18:18:50","slug":"epoqa-alba-himalaya","status":"publish","type":"product","link":"https:\/\/mosareldecor.com\/index.php\/product\/epoqa-alba-himalaya\/","title":{"rendered":"EPOQA HIMALAYA"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h2 id=\"especificaciones\">RECOMENDACIONES PARA UN ACABADO EXCEPCIONAL<\/h2>\n<p><strong>PREPARA<\/strong> Mezcla muy bien el producto antes de usarlo. La superficie debe estar limpia, seca y estable, libre de suciedad, grasa, moho o part\u00edculas sueltas. Si tienes dudas sobre la adherencia,<br \/>\naplica una capa de nuestro <a href=\"https:\/\/mosareldecor.com\/index.php\/product\/primer-universal\/\"><strong>PRIMER<\/strong> <\/a>(imprimaci\u00f3n universal), especialmente en superficies con manchas (caf\u00e9, t\u00e9, nicotina, humo).<\/p>\n<p><strong>SUPERFICIES BRILLANTES, BARNIZADAS, PL\u00c1STICOS O DE ALTO USO<\/strong><br \/>\nLija suavemente para abrir el poro y mejorar el anclaje. Aseg\u00farate que no existan restos de cera o grasa. Aplica una capa de nuestro PRIMER (imprimaci\u00f3n universal) antes de pintar.<\/p>\n<p><strong>MADERAS EN CRUDO CON TANINOS<\/strong><br \/>\nEn maderas como roble, pino, casta\u00f1o o caoba, aplica una capa de nuestro <a href=\"https:\/\/mosareldecor.com\/index.php\/product\/primer-universal\/\"><strong>PRIMER<\/strong> <\/a>(imprimaci\u00f3n universal) para evitar que los taninos alteren el color. Siempre prueba antes en una zona peque\u00f1a.<br \/>\n<strong>METAL<\/strong> Si no est\u00e1 oxidado aplica una capa de nuestro <a href=\"https:\/\/mosareldecor.com\/index.php\/product\/primer-universal\/\"><strong>PRIMER<\/strong> <\/a>(imprimaci\u00f3n universal), si est\u00e1 oxidado, retira el \u00f3xido y aplica una capa de anticorrosivo.<\/p>\n<p><strong>PINTA<\/strong> Aplica dos capas (o las necesarias) con brocha o rodillo. Considera que con rodillo normalmente se requieren m\u00e1s capas que con brocha. Seca al tacto en aproximadamente 30<br \/>\nminutos. Entre capa y capa, permite al menos 2 horas de secado. El tiempo puede variar seg\u00fan la temperatura y la humedad del ambiente. Recomendamos aplicar entre los 10 \u00b0C y 30 \u00b0C.<\/p>\n<p><strong>SELLA<\/strong> <strong>Y<\/strong> <strong>PROTEGE<\/strong> Es imprescindible sellar la pieza una vez finalizada la aplicaci\u00f3n. Para un acabado natural, c\u00e1lido y resistente, recomendamos cera Mosarel DECOR<\/p>\n<p><strong>CURADO<\/strong> Aunque la pintura seca r\u00e1pido cuando se aplica, requiere varias semanas para curar por completo; evita golpes, fricciones o uso intenso durante los primeros d\u00edas.<\/p>\n<p><strong>RENDIMIENTO<\/strong> 1 litro cubre aproximadamente 8\u201313 m\u00b2 a una mano, dependiendo de la textura y porosidad de la superficie. No es apta para exterior.<\/p>\n<p><strong>LIMPIEZA<\/strong> <strong>DE<\/strong> <strong>UTENSILIOS<\/strong><br \/>\nLimpia brochas, rodillos o herramientas con agua tibia y jab\u00f3n inmediatamente despu\u00e9s de usarlos. Evita que el producto se seque en las herramientas para prolongar su vida \u00fatil. No vac\u00edes<br \/>\nel sobrante en el drenaje y tuber\u00edas.<\/p>\n<p><strong>PRECAUCIONES<\/strong>: Puede provocar reacciones al\u00e9rgicas. Evite el contacto con los ojos; en caso de ocurrir, enjuague de inmediato con abundante agua. La hoja de seguridad est\u00e1 disponible bajo<br \/>\nsolicitud. Mantenga el producto en un lugar fresco y seco, evitando la posibilidad de congelaci\u00f3n.<br \/>\nNo almacenar a temperaturas inferiores a 5 \u00b0C ni superiores a 30 \u00b0C.<\/p>\n<p><strong>INFORMACI\u00d3N MEDIOAMBIENTAL<\/strong>: Este producto est\u00e1 formulado para ofrecer el m\u00e1ximo rendimiento con el m\u00ednimo impacto en la salud del usuario y el entorno. Contiene un m\u00e1ximo de 10 g\/L de VOC; el l\u00edmite establecido por la UE para esta categor\u00eda es de 40 g\/L. Est\u00e1 elaborado con materias primas de alta calidad, bajo olor y un impacto ambiental reducido. Contiene<br \/>\nclorometilisotiazolinona y metilisotiazolinona (3:1)<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n<hr \/>\n<p>EPOQA es una pintura de alta calidad, con tiza, elaborada en Europa y formulada para transformar tus muebles y objetos decorativos con acabados llenos de car\u00e1cter.\u00a0 Su textura suave y porosa est\u00e1 especialmente dise\u00f1ada para trabajar acabados con p\u00e1tinas de cera. Con m\u00e1s del 35% de tiza, ofrece un acabado mate profundamente pigmentado y tonos intensos.\u00a0 Permite pintar una amplia variedad de superficies \u2014 madera, madera barnizada, PVC, metal, cristal y m\u00e1s \u2014 con una preparaci\u00f3n m\u00ednima o utilizando previamente nuestro PRIMER (imprimaci\u00f3n universal). Adem\u00e1s, es baja en VOC (Compuestos Org\u00e1nicos Vol\u00e1tiles) y cumple con la normativa 2004\/42\/EC.<\/p>\n<hr \/>\n<p><strong>Tiempo de Secado:<\/strong><\/p>\n<p>Secado al tacto en 30 minutos.\u00a0 Permita secar\u00a0 2 h entre capa de pintura.\u00a0 El tiempo puede variar seg\u00fan la temperatura y la humedad del ambiente. Recomendamos aplicar entre los 10 \u00b0C y 30 \u00b0C.<\/p>\n<hr \/>\n<p><strong>Rendimiento:<\/strong><\/p>\n<p><strong>1 litro<\/strong> = 8 a 13 metros cuadrados a una mano.<\/p>\n<hr \/>\n<p>Consulta el esquema completo de aplicaci\u00f3n <a href=\"#especificaciones\"><strong>aqu\u00ed<\/strong><\/a><a href=\"https:\/\/mosareldecor.com\/index.php\/esquema-de-aplicacion-eggshell\/\">.<\/a><\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[90,99],"product_tag":[102],"class_list":["post-3784","product","type-product","status-publish","product_cat-epoqa","product_cat-epoqa_p","product_tag-pintura-con-tiza","desktop-align-center","tablet-align-left","mobile-align-left","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/mosareldecor.com\/index.php\/wp-json\/wp\/v2\/product\/3784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mosareldecor.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mosareldecor.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mosareldecor.com\/index.php\/wp-json\/wp\/v2\/comments?post=3784"}],"wp:attachment":[{"href":"https:\/\/mosareldecor.com\/index.php\/wp-json\/wp\/v2\/media?parent=3784"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mosareldecor.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=3784"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mosareldecor.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=3784"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mosareldecor.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=3784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}